{"id":9873,"date":"2024-08-25T00:27:25","date_gmt":"2024-08-25T00:27:25","guid":{"rendered":"https:\/\/mostradecinemasafricanos.com\/?p=9873"},"modified":"2026-01-02T11:43:09","modified_gmt":"2026-01-02T11:43:09","slug":"mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual","status":"publish","type":"post","link":"https:\/\/mostradecinemasafricanos.com\/en\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/","title":{"rendered":"Mostra de Cinemas Africanos acontece de 18 a 25 de setembro em Salvador com encontro in\u00e9dito do audiovisual"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"9873\" class=\"elementor elementor-9873\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-30186c36 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"30186c36\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e13c23f\" data-id=\"1e13c23f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b1f540 elementor-widget elementor-widget-text-editor\" data-id=\"8b1f540\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"text-align: center;\"><b><i>Mostra de Cinemas Africanos acontece de 18 a 25 de setembro em Salvador com encontro in\u00e9dito do audiovisual<\/i><\/b><\/h3><p style=\"text-align: center;\"><i><span style=\"font-weight: 400;\">Programa\u00e7\u00e3o inclui filmes in\u00e9ditos no Brasil, sess\u00f5es com marcos hist\u00f3ricos, presen\u00e7a de cineastas e\u00a0 mais de 50 profissionais do audiovisual africano e brasileiro<\/span><\/i><\/p><p><span style=\"font-weight: 400;\">A Mostra de Cinemas Africanos realiza mais uma edi\u00e7\u00e3o em Salvador (BA), entre os dias <\/span><b>18 e 25 de setembro <\/b><span style=\"font-weight: 400;\">com sess\u00f5es no<\/span> <b>Circuito Saladearte Cinema da UFBA, Cine MAM e Cinema do Museu, al\u00e9m do<\/b> <b>Cineteatro 2 de Julho<\/b><span style=\"font-weight: 400;\"> (IRDEB &#8211; Federa\u00e7\u00e3o).<\/span> <span style=\"font-weight: 400;\">Neste ano a programa\u00e7\u00e3o na cidade baiana tamb\u00e9m \u00e9 marcada por um encontro in\u00e9dito que vai reunir mais de<\/span><b> 50 profissionais<\/b><span style=\"font-weight: 400;\"> do audiovisual africano e brasileiro, que atuam em diversos setores da cadeia de produ\u00e7\u00e3o, do roteiro \u00e0 distribui\u00e7\u00e3o. Outras atividades paralelas, como cursos, bate-papos e laborat\u00f3rio cr\u00edtico tamb\u00e9m integram a programa\u00e7\u00e3o.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Nesta edi\u00e7\u00e3o, ser\u00e3o apresentados <\/span><b>20 longas e 7 curtas de 16 pa\u00edses<\/b><span style=\"font-weight: 400;\"> do continente africano, com v\u00e1rios t\u00edtulos in\u00e9ditos no Brasil e uma curadoria de programa\u00e7\u00f5es especiais que giram em torno de marcos hist\u00f3ricos como os <\/span><b>30 anos de liberdade na \u00c1frica do Sul<\/b><span style=\"font-weight: 400;\">,<\/span><b> 30 anos do genoc\u00eddio em Ruanda<\/b><span style=\"font-weight: 400;\"> e o <\/span><b>centen\u00e1rio de Am\u00edlcar Cabral (1924-1973)<\/b><span style=\"font-weight: 400;\">, ic\u00f4nico l\u00edder revolucion\u00e1rio da Guin\u00e9-Bissau e de Cabo Verde.<\/span><\/p><p><span style=\"font-weight: 400;\">A abertura do festival acontece dia <\/span><b>18 de setembro<\/b><span style=\"font-weight: 400;\">, no <\/span><b>Cineteatro 2 de Julho<\/b><span style=\"font-weight: 400;\"> (IRDEB &#8211; Federa\u00e7\u00e3o), \u00e0s <\/span><b>20h<\/b><span style=\"font-weight: 400;\">, com exibi\u00e7\u00e3o do filme <\/span><em><b>Banel &amp; Adama <\/b><\/em><span style=\"font-weight: 400;\">(2023), da jovem franco-senegalesa <\/span><b>Ramata-Toulaye Sy<\/b><span style=\"font-weight: 400;\">. O conto senegal\u00eas acompanha um jovem casal de uma pequena aldeia confrontado pelas conven\u00e7\u00f5es da sua comunidade. O filme, concorreu \u00e0 Palma de Ouro no Festival de Cannes 2023 e faz sua pr\u00e9-estreia comercial no Brasil durante a Mostra. Outro destaque \u00e9 o longa <\/span><em><b>Black Tea &#8211; O Aroma do Amor<\/b><\/em><span style=\"font-weight: 400;\">\u00a0(2024), de <\/span><b>Abderrahmane Sissako,<\/b><span style=\"font-weight: 400;\"> um dos cineastas mais consagrados do continente africano. O longa, in\u00e9dito no Brasil, conta a hist\u00f3ria de uma jovem da Costa do Marfim que se apaixona por um homem chin\u00eas mais velho, ap\u00f3s imigrar para a \u00c1sia. <\/span><b>Ambos os cineastas estar\u00e3o presentes na programa\u00e7\u00e3o do festival.<\/b><\/p><p><span style=\"font-weight: 400;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-6560 alignleft\" src=\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-ssa24-819x1024.jpg\" alt=\"\" width=\"480\" height=\"600\" srcset=\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-ssa24-819x1024.jpg 819w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-ssa24-240x300.jpg 240w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-ssa24-768x960.jpg 768w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-ssa24-10x12.jpg 10w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-ssa24-60x75.jpg 60w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-ssa24-480x600.jpg 480w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-ssa24.jpg 1024w\" sizes=\"(max-width:767px) 480px, 480px\" \/>Entre os filmes estreantes no Brasil que tamb\u00e9m contar\u00e3o com a presen\u00e7a dos seus realizadores, est\u00e3o a docufic\u00e7\u00e3o <\/span><b><em>Pirinha<\/em> (2024)<\/b><span style=\"font-weight: 400;\">, da cabo-verdiana <\/span><b>Natasha Craveiro,<\/b><span style=\"font-weight: 400;\"> que apresenta a jornada de uma jovem lutando para libertar-se das masmorras de seu subconsciente e dos traumas de inf\u00e2ncia. Da<\/span><b> \u00c1frica do Sul<\/b><span style=\"font-weight: 400;\">, o document\u00e1rio <\/span><b><em>Banido<\/em> <\/b><span style=\"font-weight: 400;\">(2024), de <\/span><b>Naledi Bogacwi, <\/b><span style=\"font-weight: 400;\">narra os acontecimentos em torno do filme <em>Joe Bullet<\/em> (1973), composto totalmente por pessoas africanas negras e banido pelo governo do apartheid. J\u00e1 o nigeriano <\/span><b>Dika Ofoma<\/b><span style=\"font-weight: 400;\"> discute as complexidades das rela\u00e7\u00f5es comunit\u00e1rias e familiares em um contexto de tens\u00e3o pol\u00edtica no curta <\/span><em><b>Uma Segunda-feira Tranquila <\/b><\/em><span style=\"font-weight: 400;\">(2023).<\/span><\/p><p><span style=\"font-weight: 400;\">A Mostra de Cinemas Africanos 2024, \u00fanico festival no Brasil dedicado exclusivamente \u00e0 exibi\u00e7\u00e3o de filmes africanos contempor\u00e2neos, tem curadoria de longas-metragens assinada por Ana Camila Esteves, diretora e idealizadora do evento, e pela programadora senegalesa Ibee Ndaw. \u201cMais uma vez, reafirmamos nosso compromisso de trazer ao Brasil o melhor dos cinemas africanos recentes, permitindo ao p\u00fablico brasileiro conhecer e apreciar a riqueza e diversidade dessas cinematografias\u201d, afirma Ana Camila. Ela tamb\u00e9m destaca a import\u00e2ncia da Mostra em promover a produ\u00e7\u00e3o de conte\u00fado sobre o cinema africano: \u201c\u00c9 essencial para n\u00f3s abordar os acontecimentos que marcaram a Hist\u00f3ria da \u00c1frica, como os traumas do genoc\u00eddio de Ruanda e do apartheid na \u00c1frica do Sul, que ainda ressoam no imagin\u00e1rio dos cineastas desses pa\u00edses. Da mesma forma, celebrar o centen\u00e1rio do l\u00edder revolucion\u00e1rio Am\u00edlcar Cabral \u00e9 uma forma de homenagear as hist\u00f3rias de resist\u00eancia dos povos africanos como um todo\u201d.<\/span><\/p><p><b>Conhe\u00e7a as programa\u00e7\u00f5es especiais desta edi\u00e7\u00e3o:<\/b><\/p><p><b>Foco 30 anos de Liberdade na \u00c1frica do Sul<\/b><\/p><p><span style=\"font-weight: 400;\">Com curadoria de Marcelo Esteves e em parceria com o Durban International Film Festival (DIFF), a Mostra de Cinemas Africanos oferece uma programa\u00e7\u00e3o especial de filmes que discutem os traumas, as controv\u00e9rsias e os desdobramentos do regime do apartheid, cujo fim, em 1994, completa tr\u00eas d\u00e9cadas este ano.\u00a0<\/span><\/p><p><b>Especial Centen\u00e1rio Am\u00edlcar Cabral<\/b><\/p><p><span style=\"font-weight: 400;\">Programa\u00e7\u00e3o especial que reflete sobre o legado do l\u00edder revolucion\u00e1rio Am\u00edlcar Cabral (1924-1973), nas comunidades cabo-verdianas e guineenses. O foco da curadoria inclui filmes que exploram sua influ\u00eancia e repercuss\u00e3o.\u00a0<\/span><\/p><p><b>Especial 30 anos do genoc\u00eddio em Ruanda<\/b><\/p><p><span style=\"font-weight: 400;\">Um dos eventos mais devastadores do s\u00e9culo XX, que assassinou quase um milh\u00e3o de pessoas das etnias t\u00fatsi, tu\u00e1 e hut\u00fa, deixando marcas profundas na sociedade ruandesa. Esta programa\u00e7\u00e3o destaca filmes que exploram as cicatrizes deixadas pelo genoc\u00eddio, convidando para uma reflex\u00e3o sobre as complexas din\u00e2micas sociais e hist\u00f3ricas de Ruanda.<\/span><\/p><p><b>Foco Madagascar<\/b><\/p><p><span style=\"font-weight: 400;\">Nesta sele\u00e7\u00e3o de filmes de produ\u00e7\u00e3o local e diasp\u00f3rica, s\u00e3o retratados personagens que enfrentam quest\u00f5es profundas de identidade, viol\u00eancia e resist\u00eancia em um contexto malgaxe. Cada obra revela como as hist\u00f3rias pessoais e coletivas se entrela\u00e7am para formar um retrato complexo e evocativo de uma na\u00e7\u00e3o.<\/span><\/p><p><b>Programa\u00e7\u00e3o Especial: Direito \u00e0 arte, \u00e0 terra e ao luto<\/b><\/p><p><span style=\"font-weight: 400;\">Uma sele\u00e7\u00e3o de filmes que tratam da explora\u00e7\u00e3o colonial, racismo e epistemic\u00eddio, integram um programa especial na Mostra de Cinemas Africanos 2024. Com curadoria de Ana Camila Esteves, Gabriela Almeida e Emi Koide, esta sess\u00e3o exibe curtas e longas documentais que tematizam, de diferentes formas, o trauma e o luto da viol\u00eancia colonial e o direito \u00e0 restitui\u00e7\u00e3o de objetos, obras de arte e restos mortais.<\/span><\/p><p><b>Retrospectiva Mostra de Cinemas Africanos<\/b><\/p><p><span style=\"font-weight: 400;\">A programa\u00e7\u00e3o revisita os t\u00edtulos mais populares exibidos desde a primeira edi\u00e7\u00e3o da Mostra, em 2018. As exibi\u00e7\u00f5es, que acontecem no Cine MAM e no Cineteatro 2 de Julho, trazem de volta filmes que foram sucesso de p\u00fablico, oferecendo uma nova oportunidade para apreciar essas obras que conquistaram os espectadores ao longo dos anos. Seja para rever filmes queridos ou descobri-los pela primeira vez, a Retrospectiva convida o p\u00fablico a revisitar marcos importantes do cinema africano contempor\u00e2neo.<\/span><\/p><p><b>Atividades Paralelas<\/b><\/p><p><span style=\"font-weight: 400;\">A partir de sua miss\u00e3o em difundir conhecimento, produzir conte\u00fado e promover o di\u00e1logo entre a produ\u00e7\u00e3o audiovisual africana e brasileira, a Mostra de Cinemas Africanos tamb\u00e9m realiza atividades paralelas. Nesta edi\u00e7\u00e3o ser\u00e3o realizados o Minicurso <\/span><b>Constru\u00e7\u00f5es Cinematogr\u00e1ficas de Am\u00edlcar Cabral: Reflex\u00f5es sobre os Cinemas Africanos e suas Narrativas<\/b><span style=\"font-weight: 400;\">, com facilita\u00e7\u00e3o da pesquisadora, doutora em Comunica\u00e7\u00e3o, Cultura e Artes <\/span><b>Jusciele Oliveira<\/b><span style=\"font-weight: 400;\">,<\/span> <span style=\"font-weight: 400;\">e o<\/span><b> Laborat\u00f3rio Cr\u00edtico<\/b><span style=\"font-weight: 400;\">, conduzido pelo jornalista e cr\u00edtico de cinema <\/span><b>Rafael Carvalho. <\/b><span style=\"font-weight: 400;\">As atividades acontecem gratuitamente no <\/span><b>Museu de Arte Contempor\u00e2nea da Bahia,<\/b><span style=\"font-weight: 400;\"> entre os dias <\/span><b>17 e 24 de setembro<\/b><span style=\"font-weight: 400;\">. A programa\u00e7\u00e3o completa est\u00e1 no site: <\/span><a href=\"https:\/\/mostradecinemasafricanos.com\/en\/\"><span style=\"font-weight: 400;\">www.mostradecinemasafricanos.com<\/span><\/a><\/p><p><span style=\"font-weight: 400;\">A Mostra de Cinemas Africanos em Salvador-Bahia tem apoio financeiro do Governo do Estado, atrav\u00e9s do Fundo de Cultura, Secretaria da Fazenda e Secretaria de Cultura da Bahia.<\/span><\/p><p><b>Encontros do Audiovisual Brasil-\u00c1frica<\/b><\/p><p><span style=\"font-weight: 400;\">Como parte da programa\u00e7\u00e3o 2024, a Mostra de Cinemas Africanos promove entre os dias <\/span><b>19 e 22 de setembro<\/b><span style=\"font-weight: 400;\">, a primeira edi\u00e7\u00e3o dos Encontros do Audiovisual Brasil-\u00c1frica, iniciativa que fomenta parcerias e colabora\u00e7\u00f5es entre o cinema africano e o brasileiro. O evento re\u00fane mais de<\/span><b> 50 profissionais<\/b><span style=\"font-weight: 400;\"> de ambos os lados do Atl\u00e2ntico Sul e busca criar um espa\u00e7o prop\u00edcio para a colabora\u00e7\u00e3o, onde conhecimentos e experi\u00eancias possam ser trocados para impulsionar as ind\u00fastrias cinematogr\u00e1ficas dos dois territ\u00f3rios. As atividades acontecem no <\/span><b>Cineteatro 2 de Julho<\/b><span style=\"font-weight: 400;\"> (IRDEB &#8211; Federa\u00e7\u00e3o).<\/span><\/p><p><span style=\"font-weight: 400;\">A programa\u00e7\u00e3o acontece em torno de quatro pilares: Pesquisa, Produ\u00e7\u00e3o, Difus\u00e3o e Forma\u00e7\u00e3o. Especialistas do Brasil e da \u00c1frica ir\u00e3o compartilhar conhecimentos e fomentar novos projetos de coprodu\u00e7\u00e3o, visando que o cinema africano e brasileiro ganhem ainda mais for\u00e7a e alcance. Ser\u00e3o quatro dias de atividades intensas que incluem mesas-redondas, apresenta\u00e7\u00f5es de profissionais do cinema e um f\u00f3rum dedicado a discutir a constru\u00e7\u00e3o de uma coopera\u00e7\u00e3o sustent\u00e1vel entre Brasil e \u00c1frica na ind\u00fastria criativa, com \u00eanfase no cinema.\u00a0<\/span><\/p><p><b>A participa\u00e7\u00e3o \u00e9 gratuita <\/b><span style=\"font-weight: 400;\">e limitada ao n\u00famero de vagas de cada atividade. A programa\u00e7\u00e3o completa e as inscri\u00e7\u00f5es podem ser ecnontradas no site: <\/span><a href=\"https:\/\/mostradecinemasafricanos.com\/en\/\"><span style=\"font-weight: 400;\">www.mostradecinemasafricanos.com<\/span><\/a><\/p><p><span style=\"font-weight: 400;\">O projeto Encontros do Audiovisual Brasil-\u00c1frica\u00a0 foi contemplado nos Editais da Paulo Gustavo Bahia e tem apoio financeiro do Governo do Estado da Bahia atrav\u00e9s da Secretaria de Cultura via Lei Paulo Gustavo, direcionada pelo Minist\u00e9rio da Cultura, Governo Federal. Paulo Gustavo Bahia (PGBA) foi criada para a efetiva\u00e7\u00e3o das a\u00e7\u00f5es emergenciais de apoio ao setor cultural, visando cumprir a Lei Complementar n\u00ba 195, de 8 de julho de 2022.<\/span><\/p><p><b>Servi\u00e7o:<\/b><\/p><p><b>Mostra de Cinemas Africanos 2024<\/b><\/p><p><b>Salvador (BA):<\/b><span style=\"font-weight: 400;\"> 18 a 25 de setembro<\/span><\/p><p><b>Exibi\u00e7\u00e3o de filmes: <\/b><span style=\"font-weight: 400;\">Cineteatro 2 de Julho, Circuito Saladearte Cinema da UFBA, Cinema do Museu e Cine MAM;\u00a0<\/span><\/p><p><b>Encontros do Audiovisual Brasil-\u00c1frica:<\/b> <b>Cineteatro 2 de Julho<\/b><span style=\"font-weight: 400;\"> (IRDEB &#8211; Federa\u00e7\u00e3o).<\/span><\/p><p><b>Atividades Paralelas: <\/b><span style=\"font-weight: 400;\">Museu de Arte Contempor\u00e2nea da Bahia<\/span><\/p><p><b>Filmes: <\/b><i><span style=\"font-weight: 400;\">8 dias,<\/span><\/i> <i><span style=\"font-weight: 400;\">20\u00a0 longas, 7 curtas e 16 pa\u00edses<\/span><\/i><\/p><p><b>Cineastas africanos convidados:<\/b> <b>Abderrahmane Sissako<\/b><span style=\"font-weight: 400;\"> (Maurit\u00e2nia),\u00a0 <\/span><b>Ramata-Toulaye Sy <\/b><span style=\"font-weight: 400;\">(Fran\u00e7a\/ Senegal), <\/span><b>Natasha Craveiro <\/b><span style=\"font-weight: 400;\">(Cabo Verde), <\/span><b>Naledi Bogacwi <\/b><span style=\"font-weight: 400;\">(\u00c1frica do Sul), <\/span><b>Dika Ofoma <\/b><span style=\"font-weight: 400;\">(Nig\u00e9ria)<\/span><\/p><p><b>Programa\u00e7\u00e3o completa: <\/b><a href=\"http:\/\/mostradecinemasafricanos.com\/en\/\"><span style=\"font-weight: 400;\">mostradecinemasafricanos.com<\/span><\/a><\/p><p><b>LONGAS<\/b><\/p><p><em><b>Adeus, Julia<\/b><\/em><span style=\"font-weight: 400;\"> (<em>Goodbye Julia<\/em>, Sud\u00e3o, Egito, Alemanha, Fran\u00e7a, Ar\u00e1bia Saudita, Su\u00e9cia: 2023), dir.: Mohamed Kordofani &#8211; <\/span><a href=\"https:\/\/www.youtube.com\/watch?v=Xh8sauNG4AE\"><span style=\"font-weight: 400;\">Trailer<\/span><\/a><span style=\"font-weight: 400;\">;<\/span><\/p><p><em><b>A Sepultura Vazia<\/b><\/em><span style=\"font-weight: 400;\"> (<em>The Empty Grave<\/em>, Tanz\u00e2nia, Alemanha: 2024), dir.: Agnes Lisa Wegner e Cece Mlay;<\/span><\/p><p><em><b>Banel &amp; Adama<\/b><\/em><span style=\"font-weight: 400;\"> (Banel &amp; Adama, Senegal, Fran\u00e7a, Mali: 2023), dir: .Ramata-Toulaye Sy &#8211; <\/span><a href=\"https:\/\/www.youtube.com\/watch?v=e1HKkLg26YI\"><span style=\"font-weight: 400;\">Trailer<\/span><\/a><span style=\"font-weight: 400;\">;<\/span><\/p><p><em><b>Banido<\/b><\/em><span style=\"font-weight: 400;\"> (<em>Banned<\/em>, \u00c1frica do Sul: 2024), dir.: Naledi Bogacwi;<\/span><\/p><p><em><b>Black Tea \u2013 O Aroma do Amor <\/b><\/em><span style=\"font-weight: 400;\">(<em>Black Tea<\/em>, Fran\u00e7a, Luxemburgo, Taiwan, Maurit\u00e2nia: 2024), dir. Abderrahmane Sissako &#8211; <\/span><a href=\"https:\/\/www.youtube.com\/watch?v=x0VounGKaqo\"><span style=\"font-weight: 400;\">Trailer<\/span><\/a>;<\/p><p><em><b>Dente por Dente<\/b><\/em><span style=\"font-weight: 400;\"> (<em>Dent pour dent<\/em>, Senegal, B\u00e9lgica, Fran\u00e7a, Ruanda: 2023), dir.: Ottis Ba;<\/span><\/p><p><em><b>Depois das Longas Chuvas <\/b><\/em><span style=\"font-weight: 400;\">(<em>Baada Ya Masika<\/em>, Qu\u00eania, Su\u00ed\u00e7a: 2023), dir.: Damien Hauser;<\/span><\/p><p><em><b>Dia dos Pais <\/b><\/em><span style=\"font-weight: 400;\">(<em>Father\u2019s Day<\/em>, Ruanda: 2022), dir.: Kivu Ruhorahoza;<\/span><\/p><p><em><b>Didy<\/b><\/em><span style=\"font-weight: 400;\"> (<em>Didy<\/em>, Su\u00ed\u00e7a: 2024),dir.: Ga\u00ebl Kamilindi e Fran\u00e7ois-Xavier Destors;<\/span><\/p><p><em><b>Disco Afrika: Uma Hist\u00f3ria de Madagascar<\/b><\/em><span style=\"font-weight: 400;\"> (<em>Disco Afrika: A Malagasy Story<\/em>, Fran\u00e7a, Alemanha, Ilhas Maur\u00edcio, Catar, \u00c1frica do Sul: 2023), dir.: Luck Razanajaona;<\/span><\/p><p><em><b>Donga <\/b><\/em><span style=\"font-weight: 400;\">(<em>Donga<\/em>,<\/span> <span style=\"font-weight: 400;\">L\u00edbia: 2023), dir.: Muhannad Lamin;<\/span><\/p><p><b>Legado: A Hist\u00f3ria Descolonizada da \u00c1frica do Sul<\/b><span style=\"font-weight: 400;\"> (Legacy: The De-colonized History of South Africa\u201d, \u00c1frica do Sul: 2024), dir.: Tara Moore;<\/span><\/p><p><b><em>N\u00e3o se Atrase para o Meu Funeral<\/em> <\/b><span style=\"font-weight: 400;\">(<em>Don\u2019t Be Late for My Funeral<\/em>, \u00c1frica do Sul: 2023), dir.: Diana Keam;<\/span><\/p><p><em><b>Nome<\/b><\/em><span style=\"font-weight: 400;\"> (<em>Nome<\/em>, Guin\u00e9-Bissau, Fran\u00e7a, Portugal, Angola: 2023), dir.: Sana N\u2019Hada;<\/span><\/p><p><em><b>Nossa Terra, Nossa Liberdade<\/b><\/em><span style=\"font-weight: 400;\"> (<em>Our Land, Our Freedom<\/em>, Qu\u00eania, Portugal, EUA: 2023), dir.: Meena Nanji e Zippy Kimundu;<\/span><\/p><p><em><b>Homem Novo<\/b><\/em><span style=\"font-weight: 400;\"> (<em>Omi Nobu<\/em>, Cabo Verde: 2023), dir.: Carlos Yuri Ceuninck;<\/span><\/p><p><em><b>Os Recrutas de Londres<\/b><\/em><span style=\"font-weight: 400;\"> (<em>London Recruits<\/em>, \u00c1frica do Sul: 2024), dir. Gordon Main;<\/span><\/p><p><b><em>Pirinha<\/em> <\/b><span style=\"font-weight: 400;\">(<em>Pirinha<\/em>, Cabo Verde: 2024), dir.: Natasha Craveiro;<\/span><\/p><p><b><em>Todas as Cores do Mundo Est\u00e3o Entre o Preto e o Branco<\/em>\u00a0<\/b><span style=\"font-weight: 400;\">(All the Colours of the World are Between Black and White, Nig\u00e9ria: 2023), dir: Babatunde Apalowo;<\/span><\/p><p><em><b>Zaho Zay <\/b><\/em><span style=\"font-weight: 400;\">(<em>Zaho Zay<\/em>, Madagascar, \u00c1ustria, Fran\u00e7a: 2020), dir.: Ma\u00e9va Rana\u00efvojaona e Georg Tiller.<\/span><\/p><p><b>CURTAS<\/b><\/p><p><em><b>A Espera <\/b><\/em><span style=\"font-weight: 400;\">(<em>The Wait<\/em>, \u00c1frica do Sul: 2023), dir.: Imran Hamdulay;<\/span><\/p><p><em><b>A Hist\u00f3ria de Ne Kuko <\/b><\/em><span style=\"font-weight: 400;\">(<em>The Story of Ne Kuko<\/em>, Pa\u00edses Baixos: 2023), dir.: Festus Toll;<\/span><\/p><p><em><b>As Est\u00e1tuas Tamb\u00e9m Morrem<\/b><\/em><span style=\"font-weight: 400;\"> (<em>Les statues meurent aussi<\/em>, Fran\u00e7a: 1963), dir.: Alain Resnais, Chris Marker, Ghislain Cloquet;<\/span><\/p><p><em><b>Keba, Interrompido<\/b><\/em><span style=\"font-weight: 400;\"> (<em>Keba, Interrupted<\/em>, \u00c1frica do Sul: 2024), dir.: Meja Shoba;<\/span><\/p><p><em><b>Uma Segunda-feira Tranquila<\/b><\/em><span style=\"font-weight: 400;\">\u00a0(<\/span><span style=\"font-weight: 400;\"><em>A Quiet Monday<\/em>, Nig\u00e9ria: 2023), dir.: Dika Ofoma;<\/span><\/p><p><b><em>Voc\u00ea Me Esconde &#8211; A Coloniza\u00e7\u00e3o da Arte Africana no Museu Brit\u00e2nico<\/em><\/b><span style=\"font-weight: 400;\">\u00a0(You Hide Me &#8211; The Colonization of African Art in the British Museum, Reino Unido: 1970 ), dir.: Nii Kwate Owoo;<\/span><\/p><p><em><b>Zanatany \u2013 Quando as Mortalhas Sem Alma Sussurram <\/b><\/em><span style=\"font-weight: 400;\">(Zanatany, l\u2019empreinte des linceuls esseul\u00e9s, B\u00e9lgica, Fran\u00e7a: 2024), dir.: Hachimiya Ahamada<\/span><\/p><p><b>Acompanhe em:<\/b><\/p><p><span style=\"font-weight: 400;\">Instagram: <\/span><a href=\"https:\/\/www.instagram.com\/mostradecinemasafricanos\/\"><span style=\"font-weight: 400;\">@mostradecinemasafricanos<\/span><\/a><\/p><p><span style=\"font-weight: 400;\">X:<\/span><a href=\"http:\/\/x.com\/mcafricanos\"><span style=\"font-weight: 400;\"> \/mcafricanos<\/span><\/a><\/p><p><span style=\"font-weight: 400;\">Facebook: <\/span><a href=\"https:\/\/www.facebook.com\/mostradecinemasafricanos\"><span style=\"font-weight: 400;\">\/mostradecinemasafricanos<\/span><\/a><\/p><p class=\"translation-block\"><span style=\"font-weight: 400;\">Site:<\/span> <a href=\"https:\/\/mostradecinemasafricanos.com\/en\/\" target=\"_self\"><span style=\"font-weight: 400;\">www.mostradecinemasafricanos.com<\/span><\/a><\/p><p><span style=\"font-weight: 400;\">Youtube: <\/span><a href=\"https:\/\/www.youtube.com\/@CineAfrica\"><span style=\"font-weight: 400;\">\/@cineafrica<\/span><\/a><\/p><p><span style=\"font-weight: 400;\">Linkedin:<\/span><a href=\"https:\/\/www.linkedin.com\/company\/mostradecinemasafricanos\/?viewAsMember=true\"><span style=\"font-weight: 400;\"> \/mostradecinemasafricanos<\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Mostra de Cinemas Africanos acontece de 18 a 25 de setembro em Salvador com encontro in\u00e9dito do audiovisual Programa\u00e7\u00e3o inclui filmes in\u00e9ditos no Brasil, sess\u00f5es com<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>","protected":false},"author":2,"featured_media":6560,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9873","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mostra de Cinemas Africanos acontece de 18 a 25 de setembro em Salvador com encontro in\u00e9dito do audiovisual - Mostra de Cinemas Africanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mostradecinemasafricanos.com\/en\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mostra de Cinemas Africanos acontece de 18 a 25 de setembro em Salvador com encontro in\u00e9dito do audiovisual - Mostra de Cinemas Africanos\" \/>\n<meta property=\"og:description\" content=\"Mostra de Cinemas Africanos acontece de 18 a 25 de setembro em Salvador com encontro in\u00e9dito do audiovisual Programa\u00e7\u00e3o inclui filmes in\u00e9ditos no Brasil, sess\u00f5es com [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mostradecinemasafricanos.com\/en\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/\" \/>\n<meta property=\"og:site_name\" content=\"Mostra de Cinemas Africanos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mostradecinemasafricanos\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-25T00:27:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-02T11:43:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-ssa24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/\"},\"author\":{\"name\":\"Ana\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#\/schema\/person\/dd73adb8a1b08b18ecc3739f54e58de5\"},\"headline\":\"Mostra de Cinemas Africanos acontece de 18 a 25 de setembro em Salvador com encontro in\u00e9dito do audiovisual\",\"datePublished\":\"2024-08-25T00:27:25+00:00\",\"dateModified\":\"2026-01-02T11:43:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/\"},\"wordCount\":2028,\"publisher\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-ssa24.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/\",\"url\":\"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/\",\"name\":\"Mostra de Cinemas Africanos acontece de 18 a 25 de setembro em Salvador com encontro in\u00e9dito do audiovisual - Mostra de Cinemas Africanos\",\"isPartOf\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-ssa24.jpg\",\"datePublished\":\"2024-08-25T00:27:25+00:00\",\"dateModified\":\"2026-01-02T11:43:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/#primaryimage\",\"url\":\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-ssa24.jpg\",\"contentUrl\":\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-ssa24.jpg\",\"width\":1024,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/mostradecinemasafricanos.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mostra de Cinemas Africanos acontece de 18 a 25 de setembro em Salvador com encontro in\u00e9dito do audiovisual\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#website\",\"url\":\"https:\/\/mostradecinemasafricanos.com\/\",\"name\":\"Mostra de Cinemas Africanos\",\"description\":\"Brazil African Film Festival\",\"publisher\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mostradecinemasafricanos.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#organization\",\"name\":\"Mostra de Cinemas Africanos\",\"url\":\"https:\/\/mostradecinemasafricanos.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-logo-menor.png\",\"contentUrl\":\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-logo-menor.png\",\"width\":500,\"height\":387,\"caption\":\"Mostra de Cinemas Africanos\"},\"image\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/mostradecinemasafricanos\",\"https:\/\/www.instagram.com\/mostradecinemasafricanos\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#\/schema\/person\/dd73adb8a1b08b18ecc3739f54e58de5\",\"name\":\"Ana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/31935f7c64a24c63986c2c146effe16383c15913980199ed37ed324e8a83901c?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/31935f7c64a24c63986c2c146effe16383c15913980199ed37ed324e8a83901c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/31935f7c64a24c63986c2c146effe16383c15913980199ed37ed324e8a83901c?s=96&d=mm&r=g\",\"caption\":\"Ana\"},\"url\":\"https:\/\/mostradecinemasafricanos.com\/en\/author\/ana\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mostra de Cinemas Africanos acontece de 18 a 25 de setembro em Salvador com encontro in\u00e9dito do audiovisual - Mostra de Cinemas Africanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mostradecinemasafricanos.com\/en\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/","og_locale":"en_GB","og_type":"article","og_title":"Mostra de Cinemas Africanos acontece de 18 a 25 de setembro em Salvador com encontro in\u00e9dito do audiovisual - Mostra de Cinemas Africanos","og_description":"Mostra de Cinemas Africanos acontece de 18 a 25 de setembro em Salvador com encontro in\u00e9dito do audiovisual Programa\u00e7\u00e3o inclui filmes in\u00e9ditos no Brasil, sess\u00f5es com [\u2026]","og_url":"https:\/\/mostradecinemasafricanos.com\/en\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/","og_site_name":"Mostra de Cinemas Africanos","article_publisher":"https:\/\/www.facebook.com\/mostradecinemasafricanos","article_published_time":"2024-08-25T00:27:25+00:00","article_modified_time":"2026-01-02T11:43:09+00:00","og_image":[{"width":1024,"height":1280,"url":"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-ssa24.jpg","type":"image\/jpeg"}],"author":"Ana","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ana","Estimated reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/#article","isPartOf":{"@id":"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/"},"author":{"name":"Ana","@id":"https:\/\/mostradecinemasafricanos.com\/#\/schema\/person\/dd73adb8a1b08b18ecc3739f54e58de5"},"headline":"Mostra de Cinemas Africanos acontece de 18 a 25 de setembro em Salvador com encontro in\u00e9dito do audiovisual","datePublished":"2024-08-25T00:27:25+00:00","dateModified":"2026-01-02T11:43:09+00:00","mainEntityOfPage":{"@id":"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/"},"wordCount":2028,"publisher":{"@id":"https:\/\/mostradecinemasafricanos.com\/#organization"},"image":{"@id":"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/#primaryimage"},"thumbnailUrl":"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-ssa24.jpg","articleSection":["Not\u00edcias"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/","url":"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/","name":"Mostra de Cinemas Africanos acontece de 18 a 25 de setembro em Salvador com encontro in\u00e9dito do audiovisual - Mostra de Cinemas Africanos","isPartOf":{"@id":"https:\/\/mostradecinemasafricanos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/#primaryimage"},"image":{"@id":"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/#primaryimage"},"thumbnailUrl":"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-ssa24.jpg","datePublished":"2024-08-25T00:27:25+00:00","dateModified":"2026-01-02T11:43:09+00:00","breadcrumb":{"@id":"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/#primaryimage","url":"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-ssa24.jpg","contentUrl":"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-ssa24.jpg","width":1024,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-acontece-de-18-a-25-de-setembro-em-salvador-com-encontro-inedito-do-audiovisual\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mostradecinemasafricanos.com\/"},{"@type":"ListItem","position":2,"name":"Mostra de Cinemas Africanos acontece de 18 a 25 de setembro em Salvador com encontro in\u00e9dito do audiovisual"}]},{"@type":"WebSite","@id":"https:\/\/mostradecinemasafricanos.com\/#website","url":"https:\/\/mostradecinemasafricanos.com\/","name":"Mostra de Cinemas Africanos","description":"Brazil African Film Festival","publisher":{"@id":"https:\/\/mostradecinemasafricanos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mostradecinemasafricanos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/mostradecinemasafricanos.com\/#organization","name":"Mostra de Cinemas Africanos","url":"https:\/\/mostradecinemasafricanos.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/mostradecinemasafricanos.com\/#\/schema\/logo\/image\/","url":"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-logo-menor.png","contentUrl":"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-logo-menor.png","width":500,"height":387,"caption":"Mostra de Cinemas Africanos"},"image":{"@id":"https:\/\/mostradecinemasafricanos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mostradecinemasafricanos","https:\/\/www.instagram.com\/mostradecinemasafricanos\/"]},{"@type":"Person","@id":"https:\/\/mostradecinemasafricanos.com\/#\/schema\/person\/dd73adb8a1b08b18ecc3739f54e58de5","name":"Ana","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/31935f7c64a24c63986c2c146effe16383c15913980199ed37ed324e8a83901c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/31935f7c64a24c63986c2c146effe16383c15913980199ed37ed324e8a83901c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/31935f7c64a24c63986c2c146effe16383c15913980199ed37ed324e8a83901c?s=96&d=mm&r=g","caption":"Ana"},"url":"https:\/\/mostradecinemasafricanos.com\/en\/author\/ana\/"}]}},"_links":{"self":[{"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/posts\/9873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/comments?post=9873"}],"version-history":[{"count":16,"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/posts\/9873\/revisions"}],"predecessor-version":[{"id":10376,"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/posts\/9873\/revisions\/10376"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/media\/6560"}],"wp:attachment":[{"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/media?parent=9873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/categories?post=9873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/tags?post=9873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}