{"id":1468,"date":"2021-09-12T01:30:26","date_gmt":"2021-09-12T01:30:26","guid":{"rendered":"https:\/\/mostradecinemasafricanos.com\/?p=1468"},"modified":"2025-05-27T18:03:36","modified_gmt":"2025-05-27T18:03:36","slug":"sesc2021","status":"publish","type":"post","link":"https:\/\/mostradecinemasafricanos.com\/en\/sesc2021\/","title":{"rendered":"Sesc S\u00e3o Paulo apresenta Mostra de Cinemas Africanos em outubro de 2021"},"content":{"rendered":"<h2 style=\"text-align: center;\"><b>Sesc S\u00e3o Paulo apresenta Mostra de Cinemas Africanos em outubro de 2021<\/b><\/h2>\n<p style=\"text-align: center;\"><i><span style=\"font-weight: 400;\">Evento online e gratuito traz longas e curtas contempor\u00e2neos in\u00e9ditos do continente africano &#8211; com destaque para o cinema de g\u00eanero e parceria com outros festivais<\/span><\/i><\/p>\n<p style=\"text-align: center;\"><i><span style=\"font-weight: 400;\">Os filmes ficam dispon\u00edveis de 1\u00ba a 10\/10, na plataforma Sesc Digital. <\/span><\/i><i><span style=\"font-weight: 400;\">Para assistir, acesse <\/span><\/i><a href=\"http:\/\/sescsp.org.br\/cinemasafricanos\"><i><span style=\"font-weight: 400;\">sescsp.org.br\/cinemasafricanos<\/span><\/i><\/a><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-1469\" src=\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2021\/09\/Capa-Facebook_Perfil-Pessoal.png\" alt=\"\" width=\"851\" height=\"315\" srcset=\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2021\/09\/Capa-Facebook_Perfil-Pessoal.png 851w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2021\/09\/Capa-Facebook_Perfil-Pessoal-300x111.png 300w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2021\/09\/Capa-Facebook_Perfil-Pessoal-768x284.png 768w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2021\/09\/Capa-Facebook_Perfil-Pessoal-18x7.png 18w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2021\/09\/Capa-Facebook_Perfil-Pessoal-260x96.png 260w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2021\/09\/Capa-Facebook_Perfil-Pessoal-50x19.png 50w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2021\/09\/Capa-Facebook_Perfil-Pessoal-150x56.png 150w\" sizes=\"(max-width:767px) 480px, (max-width:851px) 100vw, 851px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">O <\/span><b>Sesc S\u00e3o Paulo<\/b><span style=\"font-weight: 400;\"> promove, de 1\u00ba a 10 de outubro de 2021, a <\/span><b>Mostra de Cinemas Africanos (MCA),<\/b><span style=\"font-weight: 400;\"> que exibe 30 t\u00edtulos de fic\u00e7\u00e3o e document\u00e1rio de 16 pa\u00edses, a maioria in\u00e9ditos no Brasil. O ciclo online e gratuito apresenta 12 sess\u00f5es (dez longas e dois programas de curtas), legendados em portugu\u00eas, al\u00e9m de curso e cat\u00e1logo digital. Entre os destaques da programa\u00e7\u00e3o est\u00e3o exemplos recentes do cinema de g\u00eanero da \u00c1frica do Sul, Nig\u00e9ria e Uganda, e curtas dirigidos por mulheres, com uma mostra competitiva simult\u00e2nea com o Benin e uma sele\u00e7\u00e3o de produ\u00e7\u00f5es \u00e1rabes do norte da \u00c1frica. As exibi\u00e7\u00f5es acontecem na plataforma <\/span><a href=\"http:\/\/sescsp.org.br\/cinemasafricanos\"><b>Sesc Digital<\/b><\/a><span style=\"font-weight: 400;\"> e contam com o apoio da Embaixada da Fran\u00e7a no Brasil e do Institut Fran\u00e7ais. Mais informa\u00e7\u00f5es em <\/span><a href=\"https:\/\/mostradecinemasafricanos.com\/en\/\"><span style=\"font-weight: 400;\">mostradecinemasafricanos.com<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dos dez longas da mostra, oito s\u00e3o in\u00e9ditos no Brasil. O principal foco curatorial deste ano \u00e9 o cinema de g\u00eanero. O filme de abertura \u00e9 <\/span><b>&#8220;Juju Stories&#8221; <\/b><span style=\"font-weight: 400;\">(2021), do coletivo nigeriano <\/span><b>Surreal 16<\/b><span style=\"font-weight: 400;\">, com tr\u00eas hist\u00f3rias de bruxaria dirigidas por C.J. Obasi, Abba Makama e Michael Omonua. &#8220;Em geral se vincula a ideia de cinema africano a filmes de arte ou pol\u00edtico e sempre queremos quebrar esses estere\u00f3tipos&#8221;, explica <\/span><b>Ana Camila Esteves<\/b><span style=\"font-weight: 400;\">, que divide a curadoria com <\/span><b>Beatriz Leal Riesco<\/b><span style=\"font-weight: 400;\">. Da \u00c1frica do Sul v\u00eam o <\/span><i><span style=\"font-weight: 400;\">road movie<\/span><\/i><span style=\"font-weight: 400;\"> feminista <\/span><b>&#8220;Flatland&#8221;<\/b><span style=\"font-weight: 400;\"> (2019), de Jenna Bass, e o policial ambientado no mundo do boxe <\/span><b>&#8220;Knuckle City&#8221;<\/b><span style=\"font-weight: 400;\"> (2019), de Jahmil X.T. Qubeka.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8220;Os g\u00eaneros cinematogr\u00e1ficos africanos s\u00e3o comuns e bem particulares. N\u00e3o seguem a l\u00f3gica de Hollywood, por exemplo&#8221;, conclui <\/span><b>Ana Camila<\/b><span style=\"font-weight: 400;\">. Um curso gratuito ministrado por <\/span><b>Jusciele Oliveira<\/b><span style=\"font-weight: 400;\">, que lan\u00e7a luz sobre este tema, integra o evento. Outros t\u00edtulos de fic\u00e7\u00e3o da <\/span><b>MCA<\/b><span style=\"font-weight: 400;\"> s\u00e3o o drama autoral nigeriano <\/span><b>&#8220;Para Maria&#8221; <\/b><span style=\"font-weight: 400;\">(2020) sobre depress\u00e3o p\u00f3s-parto, de Damilola Orimogunje; o drama ambientado no universo da di\u00e1spora francesa <\/span><b>&#8220;Edif\u00edcio Gagarine&#8221;<\/b><span style=\"font-weight: 400;\"> (2020), de Fanny Liatard e J\u00e9r\u00e9my Trouilh; o suspense ugand\u00eas <\/span><b>&#8220;A Garota do Moletom Amarelo&#8221; <\/b><span style=\"font-weight: 400;\">(2020), de Loukman Ali; e o sobrenatural <\/span><b>&#8220;Voc\u00ea morrer\u00e1 aos 20&#8221;<\/b><span style=\"font-weight: 400;\"> (2019), de Amjad Abu Alala, do Sud\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Os tr\u00eas longas documentais da sele\u00e7\u00e3o s\u00e3o produ\u00e7\u00f5es ligadas \u00e0 Arg\u00e9lia: <\/span><b>&#8220;Meu Primo Ingl\u00eas&#8221; <\/b><span style=\"font-weight: 400;\">(2019), de Karim Sayad, <\/span><b>&#8220;Rua do Saara, 143&#8221;<\/b><span style=\"font-weight: 400;\"> (2019), de Hassen Ferhani, e <\/span><b>&#8220;O \u00daltimo Abrigo&#8221;<\/b><span style=\"font-weight: 400;\"> (2021), de Ousmane Samassekou. Todos os filmes da mostra ficam dispon\u00edveis apenas em territ\u00f3rio brasileiro e ser\u00e3o exibidos durante toda a semana do festival, com exce\u00e7\u00e3o de <\/span><b>&#8220;Edif\u00edcio Gagarine&#8221;<\/b><span style=\"font-weight: 400;\">, online por 24 horas, e <\/span><b>&#8220;Voc\u00ea morrer\u00e1 aos 20&#8221;<\/b><span style=\"font-weight: 400;\">, com limite de 500 visualiza\u00e7\u00f5es. O cat\u00e1logo digital da mostra vir\u00e1 com material in\u00e9dito, que inclui tradu\u00e7\u00f5es de artigos de pesquisa sobre cinemas africanos, sinopses exclusivas e resenhas dos longas assinadas pelo cr\u00edtico nigeriano Dika Ofoma.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Com curadorias compartilhadas com dois festivais, os programas de curtas expandem a abrang\u00eancia dos n\u00facleos de produ\u00e7\u00e3o africana cobertas pela Mostra. O primeiro \u00e9 fruto de parceria com a <\/span><b>Mostra de Cinema \u00c1rabe Feminino <\/b><span style=\"font-weight: 400;\">(Brasil), que exibe sete filmes com tem\u00e1ticas, g\u00eaneros e formatos diversos. A curadoria \u00e9 de Analu Bambirra e Ana Camila Esteves, e abrange Sud\u00e3o, Tun\u00edsia, Marrocos, Egito e Arg\u00e9lia. J\u00e1 o segundo programa traz 13 t\u00edtulos do <\/span><b>Festival International des Films de Femmes de Cotonou <\/b><span style=\"font-weight: 400;\">2021 (Benin), dirigido por Corn\u00e9lia Glele. Produ\u00e7\u00f5es de dez pa\u00edses africanos participam desta primeira mostra competitiva da MCA, simultaneamente no Brasil e no Benin, com um j\u00fari brasileiro formado por Morgana Gama (BA), Beth\u00e2nia Maia (DF) e Mariana Angelito (RJ).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A programa\u00e7\u00e3o da Mostra de Cinemas Africanos conta ainda com apoio da Cinemateca da Embaixada da Fran\u00e7a no Brasil (<\/span><a href=\"http:\/\/www.cinefrance.com.br\"><span style=\"font-weight: 400;\">www.cinefrance.com.br<\/span><\/a><span style=\"font-weight: 400;\">) e do Institut Fran\u00e7ais, ag\u00eancia do Minist\u00e9rio das Rela\u00e7\u00f5es Exteriores e Europeias para a difus\u00e3o cultural exterior da Fran\u00e7a, que traz os longas: <\/span><b>&#8220;Voc\u00ea morrer\u00e1 aos 20&#8221;<\/b><span style=\"font-weight: 400;\">, <\/span><b>&#8220;Rua do Saara, 143&#8221;<\/b><span style=\"font-weight: 400;\"> e <\/span><b>&#8220;Edif\u00edcio Gagarine&#8221;,<\/b><span style=\"font-weight: 400;\"> e a sess\u00e3o de curtas <\/span><b>Mostra de Cinema \u00c1rabe Feminino<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><b>Mostra de Cinemas Africanos | Ano IV<\/b><\/p>\n<p><span style=\"font-weight: 400;\">De 1\u00ba a 10 de outubro de 2021 | 10 longas e 20 curtas-metragens<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Online | Gratuito | <\/span><a href=\"http:\/\/sescsp.org.br\/cinemasafricanos\"><span style=\"font-weight: 400;\">Sesc Digital<\/span><\/a><span style=\"font-weight: 400;\"> | <\/span><a href=\"https:\/\/mostradecinemasafricanos.com\/en\/\"><span style=\"font-weight: 400;\">Site oficial<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Esta edi\u00e7\u00e3o contempla 16 pa\u00edses do continente: \u00c1frica do Sul, Arg\u00e9lia, Benin, Camar\u00f5es, Egito, Madagascar, Mali, Marrocos, Maurit\u00e2nia, Nig\u00e9ria, Rep\u00fablica Centro-Africana, Ruanda, Senegal, Sud\u00e3o, Tun\u00edsia e Uganda.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Sesc S\u00e3o Paulo apresenta Mostra de Cinemas Africanos em outubro de 2021 Evento online e gratuito traz longas e curtas contempor\u00e2neos in\u00e9ditos do continente africano &#8211;<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>","protected":false},"author":2,"featured_media":2746,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1468","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sesc S\u00e3o Paulo apresenta Mostra de Cinemas Africanos em outubro de 2021 - Mostra de Cinemas Africanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mostradecinemasafricanos.com\/en\/sesc2021\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sesc S\u00e3o Paulo apresenta Mostra de Cinemas Africanos em outubro de 2021 - Mostra de Cinemas Africanos\" \/>\n<meta property=\"og:description\" content=\"Sesc S\u00e3o Paulo apresenta Mostra de Cinemas Africanos em outubro de 2021 Evento online e gratuito traz longas e curtas contempor\u00e2neos in\u00e9ditos do continente africano &#8211; [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mostradecinemasafricanos.com\/en\/sesc2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Mostra de Cinemas Africanos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mostradecinemasafricanos\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-12T01:30:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-27T18:03:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2021\/09\/pataki-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/sesc2021\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/sesc2021\/\"},\"author\":{\"name\":\"Ana\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#\/schema\/person\/dd73adb8a1b08b18ecc3739f54e58de5\"},\"headline\":\"Sesc S\u00e3o Paulo apresenta Mostra de Cinemas Africanos em outubro de 2021\",\"datePublished\":\"2021-09-12T01:30:26+00:00\",\"dateModified\":\"2025-05-27T18:03:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/sesc2021\/\"},\"wordCount\":810,\"publisher\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/sesc2021\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2021\/09\/pataki-scaled.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/sesc2021\/\",\"url\":\"https:\/\/mostradecinemasafricanos.com\/sesc2021\/\",\"name\":\"Sesc S\u00e3o Paulo apresenta Mostra de Cinemas Africanos em outubro de 2021 - Mostra de Cinemas Africanos\",\"isPartOf\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/sesc2021\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/sesc2021\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2021\/09\/pataki-scaled.jpg\",\"datePublished\":\"2021-09-12T01:30:26+00:00\",\"dateModified\":\"2025-05-27T18:03:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/sesc2021\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mostradecinemasafricanos.com\/sesc2021\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/sesc2021\/#primaryimage\",\"url\":\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2021\/09\/pataki-scaled.jpg\",\"contentUrl\":\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2021\/09\/pataki-scaled.jpg\",\"width\":2560,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/sesc2021\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/mostradecinemasafricanos.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sesc S\u00e3o Paulo apresenta Mostra de Cinemas Africanos em outubro de 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#website\",\"url\":\"https:\/\/mostradecinemasafricanos.com\/\",\"name\":\"Mostra de Cinemas Africanos\",\"description\":\"Brazil African Film Festival\",\"publisher\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mostradecinemasafricanos.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#organization\",\"name\":\"Mostra de Cinemas Africanos\",\"url\":\"https:\/\/mostradecinemasafricanos.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-logo-menor.png\",\"contentUrl\":\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-logo-menor.png\",\"width\":500,\"height\":387,\"caption\":\"Mostra de Cinemas Africanos\"},\"image\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/mostradecinemasafricanos\",\"https:\/\/www.instagram.com\/mostradecinemasafricanos\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#\/schema\/person\/dd73adb8a1b08b18ecc3739f54e58de5\",\"name\":\"Ana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/31935f7c64a24c63986c2c146effe16383c15913980199ed37ed324e8a83901c?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/31935f7c64a24c63986c2c146effe16383c15913980199ed37ed324e8a83901c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/31935f7c64a24c63986c2c146effe16383c15913980199ed37ed324e8a83901c?s=96&d=mm&r=g\",\"caption\":\"Ana\"},\"url\":\"https:\/\/mostradecinemasafricanos.com\/en\/author\/ana\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sesc S\u00e3o Paulo apresenta Mostra de Cinemas Africanos em outubro de 2021 - Mostra de Cinemas Africanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mostradecinemasafricanos.com\/en\/sesc2021\/","og_locale":"en_GB","og_type":"article","og_title":"Sesc S\u00e3o Paulo apresenta Mostra de Cinemas Africanos em outubro de 2021 - Mostra de Cinemas Africanos","og_description":"Sesc S\u00e3o Paulo apresenta Mostra de Cinemas Africanos em outubro de 2021 Evento online e gratuito traz longas e curtas contempor\u00e2neos in\u00e9ditos do continente africano &#8211; [\u2026]","og_url":"https:\/\/mostradecinemasafricanos.com\/en\/sesc2021\/","og_site_name":"Mostra de Cinemas Africanos","article_publisher":"https:\/\/www.facebook.com\/mostradecinemasafricanos","article_published_time":"2021-09-12T01:30:26+00:00","article_modified_time":"2025-05-27T18:03:36+00:00","og_image":[{"width":2560,"height":1350,"url":"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2021\/09\/pataki-scaled.jpg","type":"image\/jpeg"}],"author":"Ana","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ana","Estimated reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mostradecinemasafricanos.com\/sesc2021\/#article","isPartOf":{"@id":"https:\/\/mostradecinemasafricanos.com\/sesc2021\/"},"author":{"name":"Ana","@id":"https:\/\/mostradecinemasafricanos.com\/#\/schema\/person\/dd73adb8a1b08b18ecc3739f54e58de5"},"headline":"Sesc S\u00e3o Paulo apresenta Mostra de Cinemas Africanos em outubro de 2021","datePublished":"2021-09-12T01:30:26+00:00","dateModified":"2025-05-27T18:03:36+00:00","mainEntityOfPage":{"@id":"https:\/\/mostradecinemasafricanos.com\/sesc2021\/"},"wordCount":810,"publisher":{"@id":"https:\/\/mostradecinemasafricanos.com\/#organization"},"image":{"@id":"https:\/\/mostradecinemasafricanos.com\/sesc2021\/#primaryimage"},"thumbnailUrl":"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2021\/09\/pataki-scaled.jpg","articleSection":["Not\u00edcias"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/mostradecinemasafricanos.com\/sesc2021\/","url":"https:\/\/mostradecinemasafricanos.com\/sesc2021\/","name":"Sesc S\u00e3o Paulo apresenta Mostra de Cinemas Africanos em outubro de 2021 - Mostra de Cinemas Africanos","isPartOf":{"@id":"https:\/\/mostradecinemasafricanos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mostradecinemasafricanos.com\/sesc2021\/#primaryimage"},"image":{"@id":"https:\/\/mostradecinemasafricanos.com\/sesc2021\/#primaryimage"},"thumbnailUrl":"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2021\/09\/pataki-scaled.jpg","datePublished":"2021-09-12T01:30:26+00:00","dateModified":"2025-05-27T18:03:36+00:00","breadcrumb":{"@id":"https:\/\/mostradecinemasafricanos.com\/sesc2021\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mostradecinemasafricanos.com\/sesc2021\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/mostradecinemasafricanos.com\/sesc2021\/#primaryimage","url":"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2021\/09\/pataki-scaled.jpg","contentUrl":"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2021\/09\/pataki-scaled.jpg","width":2560,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/mostradecinemasafricanos.com\/sesc2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mostradecinemasafricanos.com\/"},{"@type":"ListItem","position":2,"name":"Sesc S\u00e3o Paulo apresenta Mostra de Cinemas Africanos em outubro de 2021"}]},{"@type":"WebSite","@id":"https:\/\/mostradecinemasafricanos.com\/#website","url":"https:\/\/mostradecinemasafricanos.com\/","name":"Mostra de Cinemas Africanos","description":"Brazil African Film Festival","publisher":{"@id":"https:\/\/mostradecinemasafricanos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mostradecinemasafricanos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/mostradecinemasafricanos.com\/#organization","name":"Mostra de Cinemas Africanos","url":"https:\/\/mostradecinemasafricanos.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/mostradecinemasafricanos.com\/#\/schema\/logo\/image\/","url":"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-logo-menor.png","contentUrl":"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-logo-menor.png","width":500,"height":387,"caption":"Mostra de Cinemas Africanos"},"image":{"@id":"https:\/\/mostradecinemasafricanos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mostradecinemasafricanos","https:\/\/www.instagram.com\/mostradecinemasafricanos\/"]},{"@type":"Person","@id":"https:\/\/mostradecinemasafricanos.com\/#\/schema\/person\/dd73adb8a1b08b18ecc3739f54e58de5","name":"Ana","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/31935f7c64a24c63986c2c146effe16383c15913980199ed37ed324e8a83901c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/31935f7c64a24c63986c2c146effe16383c15913980199ed37ed324e8a83901c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/31935f7c64a24c63986c2c146effe16383c15913980199ed37ed324e8a83901c?s=96&d=mm&r=g","caption":"Ana"},"url":"https:\/\/mostradecinemasafricanos.com\/en\/author\/ana\/"}]}},"_links":{"self":[{"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/posts\/1468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/comments?post=1468"}],"version-history":[{"count":3,"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/posts\/1468\/revisions"}],"predecessor-version":[{"id":1625,"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/posts\/1468\/revisions\/1625"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/media\/2746"}],"wp:attachment":[{"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/media?parent=1468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/categories?post=1468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/tags?post=1468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}