{"id":12930,"date":"2025-09-24T22:38:27","date_gmt":"2025-09-24T22:38:27","guid":{"rendered":"https:\/\/mostradecinemasafricanos.com\/?p=12930"},"modified":"2025-12-31T12:30:42","modified_gmt":"2025-12-31T12:30:42","slug":"entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos","status":"publish","type":"post","link":"https:\/\/mostradecinemasafricanos.com\/en\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/","title":{"rendered":"Entre Lagos e Salvador: O Fardo da Nig\u00e9ria conecta realidades e emociona p\u00fablico na Mostra de Cinemas Africanos"},"content":{"rendered":"<h2 style=\"text-align: center;\"><b>Entre Lagos e Salvador: <\/b><b><i>O Fardo da Nig\u00e9ria<\/i><\/b><b> conecta realidades e emociona p\u00fablico na Mostra de Cinemas Africanos<\/b><\/h2>\n<h4 style=\"text-align: center;\"><i><span style=\"font-weight: 400;\">Filme da diretora Ema Edosio tra\u00e7a narrativa sobre desigualdades sociais e inspira o p\u00fablico a refletir sobre a luta por dignidade e a realiza\u00e7\u00e3o de sonhos<\/span><\/i><\/h4>\n<p style=\"text-align: right;\"><strong>Por Bia Nascimento<\/strong><\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_12937\" style=\"width: 779px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-12937\" class=\"wp-image-12937\" src=\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9266-1-scaled-e1758750927582-1024x663.jpg\" alt=\"\" width=\"769\" height=\"498\" srcset=\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9266-1-scaled-e1758750927582-1024x663.jpg 1024w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9266-1-scaled-e1758750927582-300x194.jpg 300w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9266-1-scaled-e1758750927582-768x497.jpg 768w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9266-1-scaled-e1758750927582-1536x995.jpg 1536w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9266-1-scaled-e1758750927582-18x12.jpg 18w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9266-1-scaled-e1758750927582-116x75.jpg 116w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9266-1-scaled-e1758750927582-480x311.jpg 480w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9266-1-scaled-e1758750927582.jpg 1997w\" sizes=\"(max-width:767px) 480px, (max-width:769px) 100vw, 769px\" \/><p id=\"caption-attachment-12937\" class=\"wp-caption-text\">Foto Bia Nascimento<\/p><\/div>\n<p><span style=\"font-weight: 400;\">Na Saladearte Cinema da UFBA, no bairro do Canela, o p\u00fablico mergulhou em uma uma narrativa que mistura esperan\u00e7a e cr\u00edtica social na \u00faltima quinta-feira (19\/09) com a exibi\u00e7\u00e3o do filme <\/span><i><span style=\"font-weight: 400;\">O Fardo da Nig\u00e9ria (2025)<\/span><\/i><span style=\"font-weight: 400;\">, da diretora Ema Edosio. A cineasta tamb\u00e9m esteve presente durante a sess\u00e3o para um bate-papo com o p\u00fablico sobre seu terceiro longa, que teve sua estreia\u00a0 no Brasil atrav\u00e9s da Mostra de Cinemas Africanos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Natural da Nig\u00e9ria, Ema revela entusiasmo em trazer seu trabalho para o Brasil pela segunda vez,\u00a0 especialmente neste ano em que veio apresentar seu filme na capital baiana. &#8220;Salvador \u00e9 uma cidade muito linda e me lembra a cidade de Lagos, de onde eu venho. Tem sido uma experi\u00eancia incr\u00edvel. O que eu espero \u00e9 que os espectadores, especialmente os brasileiros, segurem um espelho e se vejam\u201d.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ana Ca<img decoding=\"async\" class=\"alignnone size-full wp-image-12936\" src=\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9266-1.heic\" alt=\"\" \/>mila Esteves, diretora da Mostra, conta que essa \u00e9 a segunda estreia do filme no mundo. A primeira foi no Festival Internacional de Cinema de Locarno: \u201ca gente acompanha as carreiras dos diretores. Como muitos s\u00e3o jovens e est\u00e3o fazendo seus primeiros ou segundo filmes, nossa miss\u00e3o \u00e9 acompanhar essas carreiras que est\u00e3o acontecendo, fazer com que esses filmes venham para c\u00e1 e que as pessoas conhe\u00e7am\u201d.\u00a0<\/span><\/p>\n<p><b>Sonhar tamb\u00e9m \u00e9 liberdade\u00a0<\/b><\/p>\n<div id=\"attachment_12942\" style=\"width: 261px\" class=\"wp-caption alignleft\"><img decoding=\"async\" aria-describedby=\"caption-attachment-12942\" class=\"wp-image-12942 lazyload\" data-src=\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/Ema-Edosio-dia-04-683x1024.jpg\" alt=\"\" width=\"251\" height=\"376\" data-srcset=\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/Ema-Edosio-dia-04-683x1024.jpg 683w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/Ema-Edosio-dia-04-200x300.jpg 200w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/Ema-Edosio-dia-04-768x1152.jpg 768w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/Ema-Edosio-dia-04-1024x1536.jpg 1024w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/Ema-Edosio-dia-04-8x12.jpg 8w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/Ema-Edosio-dia-04-50x75.jpg 50w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/Ema-Edosio-dia-04-480x720.jpg 480w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/Ema-Edosio-dia-04-rotated.jpg 1040w\" data-sizes=\"(max-width:767px) 251px, 251px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 251px; --smush-placeholder-aspect-ratio: 251\/376;\" \/><p id=\"caption-attachment-12942\" class=\"wp-caption-text\">Cineasta Ema Edosio em bate-papo com o p\u00fablico. Foto Fernanda Maia<\/p><\/div>\n<p><span style=\"font-weight: 400;\">O enredo de <\/span><i><span style=\"font-weight: 400;\">O fardo da Nig\u00e9ria<\/span><\/i><span style=\"font-weight: 400;\"> se constr\u00f3i com a hist\u00f3ria de cinco jovens: Fagbo, Pocco, Lighter, Movement, Colos e Poppy, um grupo de dan\u00e7arinos que luta contra o sistema vigente em um pa\u00eds marcado pela desigualdade por meio da arte. Em meio aos gritos de protestos tamb\u00e9m est\u00e3o os risos, coreografias e hist\u00f3rias de amor dos jovens sonhadores. Enquanto isso, o protagonista Fagbo lida com o adoecimento da m\u00e3e, o que acaba trazendo ainda mais debilidade para a sua vida financeira e de seus colegas.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dificuldades como essas n\u00e3o impedem que os personagens aproveitem o amor, e principalmente, a arte quando entoam: \u201cdan\u00e7a \u00e9 vida. Se pudermos dan\u00e7ar, vamos dan\u00e7ar. A \u00faltima coisa que vamos fazer \u00e9 desistir\u201d.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ema acredita que tudo se direciona para as aspira\u00e7\u00f5es de cada um. \u201cTodos n\u00f3s, \u00e0s vezes, temos sonhos que tivemos que abandonar, mas a quest\u00e3o \u00e9 por qu\u00ea e qual sistema nos faz esquecer nossos sonhos. Isso \u00e9 para os brasileiros, para os nigerianos, para que todos no mundo se levantem e lutem por seus sonhos\u201d, explica.<\/span><\/p>\n<p><b>P\u00fablico valoriza conex\u00e3o entre cinema africano e cultura baiana<\/b><\/p>\n<div id=\"attachment_12938\" style=\"width: 372px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-12938\" class=\"wp-image-12938 lazyload\" data-src=\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9247-1-1024x768.jpg\" alt=\"\" width=\"362\" height=\"271\" data-srcset=\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9247-1-1024x768.jpg 1024w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9247-1-300x225.jpg 300w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9247-1-768x576.jpg 768w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9247-1-1536x1152.jpg 1536w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9247-1-2048x1536.jpg 2048w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9247-1-16x12.jpg 16w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9247-1-100x75.jpg 100w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9247-1-480x360.jpg 480w\" data-sizes=\"(max-width:767px) 362px, 362px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 362px; --smush-placeholder-aspect-ratio: 362\/271;\" \/><p id=\"caption-attachment-12938\" class=\"wp-caption-text\">Casal acompanha edi\u00e7\u00f5es da Mostra de Cinemas Africanos. Foto Bia Nascimento<\/p><\/div>\n<p><span style=\"font-weight: 400;\">Com filmes de v\u00e1rios g\u00eaneros e nacionalidades, a Mostra de Cinemas Africanos re\u00fane diferentes p\u00fablicos, dos menos frequentadores aos que v\u00e3o ao cinema regularmente. O casal Rita Setaro e Jo\u00e3o Setaro costumam assistir filmes no circuito saladearte e j\u00e1 esteve presente em outras edi\u00e7\u00f5es da Mostra de Cinemas Africanos. \u201cEu sempre procuro filmes que n\u00e3o passam em cinemas de <\/span><i><span style=\"font-weight: 400;\">shopping<\/span><\/i><span style=\"font-weight: 400;\">, para ver uma outra variedade\u201d, comenta Jo\u00e3o\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Rita explica que, para ela, \u00e9 muito importante ter acesso a produ\u00e7\u00f5es cinematogr\u00e1ficas que mostram a cultura baiana e a heran\u00e7a do continente africano e, por isso, escolheram ver <\/span><i><span style=\"font-weight: 400;\">O Fardo da Nig\u00e9ria<\/span><\/i><span style=\"font-weight: 400;\">: \u201ca Bahia tem muito a ver com a \u00c1frica, ent\u00e3o \u00e9 muito interessante assistir filmes africanos e conseguir identificar nossa cultura l\u00e1, como heran\u00e7a\u201d.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Entre Lagos e Salvador: O Fardo da Nig\u00e9ria conecta realidades e emociona p\u00fablico na Mostra de Cinemas Africanos Filme da diretora Ema Edosio tra\u00e7a narrativa sobre<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>","protected":false},"author":3,"featured_media":12937,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12930","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entre Lagos e Salvador: O Fardo da Nig\u00e9ria conecta realidades e emociona p\u00fablico na Mostra de Cinemas Africanos - Mostra de Cinemas Africanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mostradecinemasafricanos.com\/en\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entre Lagos e Salvador: O Fardo da Nig\u00e9ria conecta realidades e emociona p\u00fablico na Mostra de Cinemas Africanos - Mostra de Cinemas Africanos\" \/>\n<meta property=\"og:description\" content=\"Entre Lagos e Salvador: O Fardo da Nig\u00e9ria conecta realidades e emociona p\u00fablico na Mostra de Cinemas Africanos Filme da diretora Ema Edosio tra\u00e7a narrativa sobre [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mostradecinemasafricanos.com\/en\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/\" \/>\n<meta property=\"og:site_name\" content=\"Mostra de Cinemas Africanos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mostradecinemasafricanos\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-24T22:38:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-31T12:30:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9266-1-scaled-e1758750927582.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1997\" \/>\n\t<meta property=\"og:image:height\" content=\"1293\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gisele Santana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gisele Santana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/\"},\"author\":{\"name\":\"Gisele Santana\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#\/schema\/person\/9b79993a8add2f124a311ee42e177691\"},\"headline\":\"Entre Lagos e Salvador: O Fardo da Nig\u00e9ria conecta realidades e emociona p\u00fablico na Mostra de Cinemas Africanos\",\"datePublished\":\"2025-09-24T22:38:27+00:00\",\"dateModified\":\"2025-12-31T12:30:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/\"},\"wordCount\":679,\"publisher\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9266-1-scaled-e1758750927582.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/\",\"url\":\"https:\/\/mostradecinemasafricanos.com\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/\",\"name\":\"Entre Lagos e Salvador: O Fardo da Nig\u00e9ria conecta realidades e emociona p\u00fablico na Mostra de Cinemas Africanos - Mostra de Cinemas Africanos\",\"isPartOf\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9266-1-scaled-e1758750927582.jpg\",\"datePublished\":\"2025-09-24T22:38:27+00:00\",\"dateModified\":\"2025-12-31T12:30:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mostradecinemasafricanos.com\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/#primaryimage\",\"url\":\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9266-1-scaled-e1758750927582.jpg\",\"contentUrl\":\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9266-1-scaled-e1758750927582.jpg\",\"width\":1997,\"height\":1293},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/mostradecinemasafricanos.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entre Lagos e Salvador: O Fardo da Nig\u00e9ria conecta realidades e emociona p\u00fablico na Mostra de Cinemas Africanos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#website\",\"url\":\"https:\/\/mostradecinemasafricanos.com\/\",\"name\":\"Mostra de Cinemas Africanos\",\"description\":\"Brazil African Film Festival\",\"publisher\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mostradecinemasafricanos.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#organization\",\"name\":\"Mostra de Cinemas Africanos\",\"url\":\"https:\/\/mostradecinemasafricanos.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-logo-menor.png\",\"contentUrl\":\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-logo-menor.png\",\"width\":500,\"height\":387,\"caption\":\"Mostra de Cinemas Africanos\"},\"image\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/mostradecinemasafricanos\",\"https:\/\/www.instagram.com\/mostradecinemasafricanos\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#\/schema\/person\/9b79993a8add2f124a311ee42e177691\",\"name\":\"Gisele Santana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/6f9f27992e0945194d18f4bd283e47724ecc88884f0ad25554a8add14e15b5bd?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6f9f27992e0945194d18f4bd283e47724ecc88884f0ad25554a8add14e15b5bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6f9f27992e0945194d18f4bd283e47724ecc88884f0ad25554a8add14e15b5bd?s=96&d=mm&r=g\",\"caption\":\"Gisele Santana\"},\"url\":\"https:\/\/mostradecinemasafricanos.com\/en\/author\/gisele\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entre Lagos e Salvador: O Fardo da Nig\u00e9ria conecta realidades e emociona p\u00fablico na Mostra de Cinemas Africanos - Mostra de Cinemas Africanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mostradecinemasafricanos.com\/en\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/","og_locale":"en_GB","og_type":"article","og_title":"Entre Lagos e Salvador: O Fardo da Nig\u00e9ria conecta realidades e emociona p\u00fablico na Mostra de Cinemas Africanos - Mostra de Cinemas Africanos","og_description":"Entre Lagos e Salvador: O Fardo da Nig\u00e9ria conecta realidades e emociona p\u00fablico na Mostra de Cinemas Africanos Filme da diretora Ema Edosio tra\u00e7a narrativa sobre [\u2026]","og_url":"https:\/\/mostradecinemasafricanos.com\/en\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/","og_site_name":"Mostra de Cinemas Africanos","article_publisher":"https:\/\/www.facebook.com\/mostradecinemasafricanos","article_published_time":"2025-09-24T22:38:27+00:00","article_modified_time":"2025-12-31T12:30:42+00:00","og_image":[{"width":1997,"height":1293,"url":"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9266-1-scaled-e1758750927582.jpg","type":"image\/jpeg"}],"author":"Gisele Santana","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Gisele Santana","Estimated reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mostradecinemasafricanos.com\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/#article","isPartOf":{"@id":"https:\/\/mostradecinemasafricanos.com\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/"},"author":{"name":"Gisele Santana","@id":"https:\/\/mostradecinemasafricanos.com\/#\/schema\/person\/9b79993a8add2f124a311ee42e177691"},"headline":"Entre Lagos e Salvador: O Fardo da Nig\u00e9ria conecta realidades e emociona p\u00fablico na Mostra de Cinemas Africanos","datePublished":"2025-09-24T22:38:27+00:00","dateModified":"2025-12-31T12:30:42+00:00","mainEntityOfPage":{"@id":"https:\/\/mostradecinemasafricanos.com\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/"},"wordCount":679,"publisher":{"@id":"https:\/\/mostradecinemasafricanos.com\/#organization"},"image":{"@id":"https:\/\/mostradecinemasafricanos.com\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/#primaryimage"},"thumbnailUrl":"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9266-1-scaled-e1758750927582.jpg","articleSection":["Not\u00edcias"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/mostradecinemasafricanos.com\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/","url":"https:\/\/mostradecinemasafricanos.com\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/","name":"Entre Lagos e Salvador: O Fardo da Nig\u00e9ria conecta realidades e emociona p\u00fablico na Mostra de Cinemas Africanos - Mostra de Cinemas Africanos","isPartOf":{"@id":"https:\/\/mostradecinemasafricanos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mostradecinemasafricanos.com\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/#primaryimage"},"image":{"@id":"https:\/\/mostradecinemasafricanos.com\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/#primaryimage"},"thumbnailUrl":"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9266-1-scaled-e1758750927582.jpg","datePublished":"2025-09-24T22:38:27+00:00","dateModified":"2025-12-31T12:30:42+00:00","breadcrumb":{"@id":"https:\/\/mostradecinemasafricanos.com\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mostradecinemasafricanos.com\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/mostradecinemasafricanos.com\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/#primaryimage","url":"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9266-1-scaled-e1758750927582.jpg","contentUrl":"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/09\/IMG_9266-1-scaled-e1758750927582.jpg","width":1997,"height":1293},{"@type":"BreadcrumbList","@id":"https:\/\/mostradecinemasafricanos.com\/entre-lagos-e-salvador-o-fardo-da-nigeria-conecta-realidades-e-emociona-publico-na-mostra-de-cinemas-africanos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mostradecinemasafricanos.com\/"},{"@type":"ListItem","position":2,"name":"Entre Lagos e Salvador: O Fardo da Nig\u00e9ria conecta realidades e emociona p\u00fablico na Mostra de Cinemas Africanos"}]},{"@type":"WebSite","@id":"https:\/\/mostradecinemasafricanos.com\/#website","url":"https:\/\/mostradecinemasafricanos.com\/","name":"Mostra de Cinemas Africanos","description":"Brazil African Film Festival","publisher":{"@id":"https:\/\/mostradecinemasafricanos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mostradecinemasafricanos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/mostradecinemasafricanos.com\/#organization","name":"Mostra de Cinemas Africanos","url":"https:\/\/mostradecinemasafricanos.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/mostradecinemasafricanos.com\/#\/schema\/logo\/image\/","url":"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-logo-menor.png","contentUrl":"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-logo-menor.png","width":500,"height":387,"caption":"Mostra de Cinemas Africanos"},"image":{"@id":"https:\/\/mostradecinemasafricanos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mostradecinemasafricanos","https:\/\/www.instagram.com\/mostradecinemasafricanos\/"]},{"@type":"Person","@id":"https:\/\/mostradecinemasafricanos.com\/#\/schema\/person\/9b79993a8add2f124a311ee42e177691","name":"Gisele Santana","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/6f9f27992e0945194d18f4bd283e47724ecc88884f0ad25554a8add14e15b5bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6f9f27992e0945194d18f4bd283e47724ecc88884f0ad25554a8add14e15b5bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6f9f27992e0945194d18f4bd283e47724ecc88884f0ad25554a8add14e15b5bd?s=96&d=mm&r=g","caption":"Gisele Santana"},"url":"https:\/\/mostradecinemasafricanos.com\/en\/author\/gisele\/"}]}},"_links":{"self":[{"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/posts\/12930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/comments?post=12930"}],"version-history":[{"count":10,"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/posts\/12930\/revisions"}],"predecessor-version":[{"id":12946,"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/posts\/12930\/revisions\/12946"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/media\/12937"}],"wp:attachment":[{"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/media?parent=12930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/categories?post=12930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/tags?post=12930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}