{"id":11922,"date":"2025-07-25T13:10:26","date_gmt":"2025-07-25T13:10:26","guid":{"rendered":"https:\/\/mostradecinemasafricanos.com\/?p=11922"},"modified":"2026-01-02T11:38:14","modified_gmt":"2026-01-02T11:38:14","slug":"mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador","status":"publish","type":"post","link":"https:\/\/mostradecinemasafricanos.com\/en\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/","title":{"rendered":"Mostra de Cinemas Africanos leva sess\u00f5es gratuitas de filmes africanos a bairros perif\u00e9ricos de Salvador"},"content":{"rendered":"<h2 style=\"text-align: center;\"><b>Mostra internacional leva sess\u00f5es gratuitas de filmes africanos a bairros perif\u00e9ricos de Salvador<\/b><\/h2>\n<p style=\"text-align: center;\"><i><span style=\"font-weight: 400;\">A partir de 31 de julho, Alagados, Cajazeiras e Engenho Velho de Brotas recebem programa\u00e7\u00e3o que integra a Mostra de Cinemas Africanos (MCA) deste ano<\/span><\/i><\/p>\n<div id=\"attachment_11923\" style=\"width: 1034px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-11923\" class=\"wp-image-11923 size-large\" src=\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/07\/01-Supa-Modo_1200-1024x576.jpg\" alt=\"\" width=\"1024\" height=\"576\" srcset=\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/07\/01-Supa-Modo_1200-1024x576.jpg 1024w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/07\/01-Supa-Modo_1200-300x169.jpg 300w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/07\/01-Supa-Modo_1200-768x432.jpg 768w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/07\/01-Supa-Modo_1200-18x10.jpg 18w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/07\/01-Supa-Modo_1200-133x75.jpg 133w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/07\/01-Supa-Modo_1200-480x270.jpg 480w, https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2025\/07\/01-Supa-Modo_1200.jpg 1200w\" sizes=\"(max-width:767px) 480px, (max-width:1024px) 100vw, 1024px\" \/><p id=\"caption-attachment-11923\" class=\"wp-caption-text\">Supa Modo (2018), de Likarion Wainaina (Qu\u00eania) &#8211; Cr\u00e9dito: One Fine Day Films<\/p><\/div>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Filmes que atravessam o Atl\u00e2ntico, quebram barreiras e chegam onde o cinema raramente alcan\u00e7a. Pela primeira vez, a <\/span><b>Mostra de Cinemas Africanos (MCA)<\/b><span style=\"font-weight: 400;\"> leva sua programa\u00e7\u00e3o para o cora\u00e7\u00e3o das <\/span><b>periferias de Salvador<\/b><span style=\"font-weight: 400;\">. \u00c9 a estreia da <\/span><b><i>Mostra nos Bairros<\/i><\/b><span style=\"font-weight: 400;\">, uma a\u00e7\u00e3o in\u00e9dita que, entre os dias <\/span><b>31 de julho e 8 de agosto<\/b><span style=\"font-weight: 400;\">, promove <\/span><b>dez sess\u00f5es gratuitas<\/b><span style=\"font-weight: 400;\"> de <\/span><b>quatro filmes africanos<\/b><span style=\"font-weight: 400;\"> em tr\u00eas espa\u00e7os culturais da cidade: Espa\u00e7o Cultural <\/span><b>Alagados<\/b><span style=\"font-weight: 400;\">, no Uruguai, Espa\u00e7o Boca de Brasa, em <\/span><b>Cajazeiras<\/b><span style=\"font-weight: 400;\">, e Funda\u00e7\u00e3o Pierre Verger, no <\/span><b>Engenho Velho de Brotas.\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">A a\u00e7\u00e3o<\/span> <span style=\"font-weight: 400;\">funcionar\u00e1 como uma pr\u00e9via da programa\u00e7\u00e3o oficial da MCA, festival internacional de cinema que acontece em setembro nas cidades de Salvador, Cachoeira e no Rio de Janeiro e, em outubro, em S\u00e3o Paulo. Com curadoria especial para jovens espectadores, a <\/span><i><span style=\"font-weight: 400;\">Mostra nos Bairros<\/span><\/i><span style=\"font-weight: 400;\"> leva ao p\u00fablico obras como <\/span><b>\u201cKasala\u201d<\/b><span style=\"font-weight: 400;\"> (Nig\u00e9ria), de Ema Edosio, <\/span><b>\u201cWallay\u201d<\/b><span style=\"font-weight: 400;\"> (Fran\u00e7a\/ Catar), de Berni Goldblat, <\/span><b>\u201cSupa Modo\u201d<\/b><span style=\"font-weight: 400;\"> (Qu\u00eania\/Alemanha), dirigido por Likarion Wainaina, e <\/span><b>\u201cMartha &amp; Niki\u201d<\/b><span style=\"font-weight: 400;\"> (Su\u00e9cia), de Tora M\u00e5rtens. Os filmes abordam temas como amadurecimento, amizade, supera\u00e7\u00e3o, ancestralidade e pertencimento.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A programa\u00e7\u00e3o come\u00e7a nos dias 31 de julho e 1\u00ba de agosto, com sess\u00f5es \u00e0s 15h30 e 19h no Espa\u00e7o Cultural Alagados, no bairro do Uruguai. Em seguida, a Mostra chega ao Espa\u00e7o Boca de Brasa Cajazeiras, nos dias 5 e 6 de agosto, com sess\u00f5es \u00e0s 14h e 19h. O ciclo se encerra na Funda\u00e7\u00e3o Pierre Verger, no Engenho Velho de Brotas, nos dias 7 e 8 de agosto, com sess\u00f5es \u00e0s 18h. A entrada \u00e9 gratuita e a programa\u00e7\u00e3o completa est\u00e1 dispon\u00edvel no site oficial da MCA: <\/span><a href=\"https:\/\/mostradecinemasafricanos.com\/en\/\"><span style=\"font-weight: 400;\">https:\/\/mostradecinemasafricanos.com\/<\/span><\/a><span style=\"font-weight: 400;\">. <\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><b>NOVOS P\u00daBLICOS<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">Segundo Ana Camila Esteves, idealizadora do festival, a Mostra nos Bairros marca a realiza\u00e7\u00e3o de um desejo antigo: \u201cUma vontade que sempre tivemos foi de levar filmes africanos para espa\u00e7os culturais parceiros na cidade de Salvador. Este ano, com a Dan Territ\u00f3rio de Cria\u00e7\u00e3o assumindo nossa realiza\u00e7\u00e3o, conseguimos avan\u00e7ar nesse sonho, e estamos s\u00f3 come\u00e7ando\u201d, destaca. Ana Camila explica que a a\u00e7\u00e3o busca articular e mobilizar os p\u00fablicos dos bairros, promovendo sess\u00f5es em espa\u00e7os que dialogam com as comunidades locais e ampliando o acesso \u00e0 programa\u00e7\u00e3o da Mostra. \u201cOs filmes foram pensados para um p\u00fablico jovem, mas as sess\u00f5es s\u00e3o abertas para qualquer idade\u201d, completa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Com realiza\u00e7\u00e3o da <\/span><b>Ana Camila Comunica\u00e7\u00e3o e Cultura<\/b><span style=\"font-weight: 400;\"> e da <\/span><b>Dan Territ\u00f3rio de Cria\u00e7\u00e3o<\/b><span style=\"font-weight: 400;\">, a Mostra nos Bairros refor\u00e7a o compromisso da Mostra de Cinemas Africanos em expandir o acesso ao cinema africano contempor\u00e2neo, descentralizando sua circula\u00e7\u00e3o e promovendo novas conex\u00f5es entre o audiovisual africano e o p\u00fablico brasileiro.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A Mostra de Cinemas Africanos 2025 acontece entre 10 a 24 de setembro e traz como foco o cinema nigeriano. Em seu 8\u00ba ano consecutivo, o festival amplia a sua presen\u00e7a nacional, acontecendo pela primeira vez no Rio de Janeiro e na cidade hist\u00f3rica de Cachoeira, no Rec\u00f4ncavo Baiano.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em Salvador, a Mostra est\u00e1 organizada no \u00e2mbito da Temporada Fran\u00e7a-Brasil 2025 \u2013 iniciativa bilateral que celebra os 200 anos de rela\u00e7\u00f5es diplom\u00e1ticas entre os dois pa\u00edses, sendo o \u00fanico festival de cinema na Bahia a integrar a programa\u00e7\u00e3o. A\u00a0 Mostra de Cinemas Africanos 2025 tem apoio financeiro do Governo do Estado, por meio do Fundo de Cultura, Secretaria da Fazenda e Secretaria de Cultura da Bahia.<\/span><\/p>\n<p><b>SERVI\u00c7O:<\/b><b><br \/>\n<\/b><b>Mostra de Cinemas Africanos 2025 &#8211; <\/b><b><i>Mostra nos Bairros<\/i><\/b><b><br \/>\n<\/b><b>Data: <\/b><span style=\"font-weight: 400;\">31 de julho e 8 de agosto<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><b>Sess\u00f5es: <\/b><span style=\"font-weight: 400;\">Espa\u00e7o Cultural Alagados (Uruguai) &#8211; 31\/07 e 1\/08, 15h30 e 19h; Espa\u00e7o Boca de Brasa (Cajazeiras) &#8211; 5 e 6\/08, 14h e 19h; Funda\u00e7\u00e3o Pierre Verger (Engenho Velho de Brotas) &#8211; 7 e 8\/08, 18h.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><b>Programa\u00e7\u00e3o: <\/b><a href=\"https:\/\/mostradecinemasafricanos.com\/en\/\"><span style=\"font-weight: 400;\">https:\/\/mostradecinemasafricanos.com\/<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><\/a><b>Entrada Gratuita<\/b><b><br \/>\n<\/b><b>Classifica\u00e7\u00e3o: <\/b><span style=\"font-weight: 400;\">14 anos<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><b>Informa\u00e7\u00f5es: <\/b><span style=\"font-weight: 400;\">@mostradecinemasafricanos<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><b>Realiza\u00e7\u00e3o: <\/b><span style=\"font-weight: 400;\">Ana Camila Comunica\u00e7\u00e3o e Cultura e Dan Territ\u00f3rio de Cria\u00e7\u00e3o<\/span><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Mostra internacional leva sess\u00f5es gratuitas de filmes africanos a bairros perif\u00e9ricos de Salvador A partir de 31 de julho, Alagados, Cajazeiras e Engenho Velho de Brotas<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>","protected":false},"author":2,"featured_media":980,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mostra de Cinemas Africanos leva sess\u00f5es gratuitas de filmes africanos a bairros perif\u00e9ricos de Salvador - Mostra de Cinemas Africanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mostradecinemasafricanos.com\/en\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mostra de Cinemas Africanos leva sess\u00f5es gratuitas de filmes africanos a bairros perif\u00e9ricos de Salvador - Mostra de Cinemas Africanos\" \/>\n<meta property=\"og:description\" content=\"Mostra internacional leva sess\u00f5es gratuitas de filmes africanos a bairros perif\u00e9ricos de Salvador A partir de 31 de julho, Alagados, Cajazeiras e Engenho Velho de Brotas [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mostradecinemasafricanos.com\/en\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/\" \/>\n<meta property=\"og:site_name\" content=\"Mostra de Cinemas Africanos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mostradecinemasafricanos\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-25T13:10:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-02T11:38:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2022\/01\/IMG_7695-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/\"},\"author\":{\"name\":\"Ana\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#\/schema\/person\/dd73adb8a1b08b18ecc3739f54e58de5\"},\"headline\":\"Mostra de Cinemas Africanos leva sess\u00f5es gratuitas de filmes africanos a bairros perif\u00e9ricos de Salvador\",\"datePublished\":\"2025-07-25T13:10:26+00:00\",\"dateModified\":\"2026-01-02T11:38:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/\"},\"wordCount\":745,\"publisher\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2022\/01\/IMG_7695-scaled.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/\",\"url\":\"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/\",\"name\":\"Mostra de Cinemas Africanos leva sess\u00f5es gratuitas de filmes africanos a bairros perif\u00e9ricos de Salvador - Mostra de Cinemas Africanos\",\"isPartOf\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2022\/01\/IMG_7695-scaled.jpg\",\"datePublished\":\"2025-07-25T13:10:26+00:00\",\"dateModified\":\"2026-01-02T11:38:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/#primaryimage\",\"url\":\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2022\/01\/IMG_7695-scaled.jpg\",\"contentUrl\":\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2022\/01\/IMG_7695-scaled.jpg\",\"width\":2560,\"height\":1438},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/mostradecinemasafricanos.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mostra de Cinemas Africanos leva sess\u00f5es gratuitas de filmes africanos a bairros perif\u00e9ricos de Salvador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#website\",\"url\":\"https:\/\/mostradecinemasafricanos.com\/\",\"name\":\"Mostra de Cinemas Africanos\",\"description\":\"Brazil African Film Festival\",\"publisher\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mostradecinemasafricanos.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#organization\",\"name\":\"Mostra de Cinemas Africanos\",\"url\":\"https:\/\/mostradecinemasafricanos.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-logo-menor.png\",\"contentUrl\":\"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-logo-menor.png\",\"width\":500,\"height\":387,\"caption\":\"Mostra de Cinemas Africanos\"},\"image\":{\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/mostradecinemasafricanos\",\"https:\/\/www.instagram.com\/mostradecinemasafricanos\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/mostradecinemasafricanos.com\/#\/schema\/person\/dd73adb8a1b08b18ecc3739f54e58de5\",\"name\":\"Ana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/31935f7c64a24c63986c2c146effe16383c15913980199ed37ed324e8a83901c?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/31935f7c64a24c63986c2c146effe16383c15913980199ed37ed324e8a83901c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/31935f7c64a24c63986c2c146effe16383c15913980199ed37ed324e8a83901c?s=96&d=mm&r=g\",\"caption\":\"Ana\"},\"url\":\"https:\/\/mostradecinemasafricanos.com\/en\/author\/ana\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mostra de Cinemas Africanos leva sess\u00f5es gratuitas de filmes africanos a bairros perif\u00e9ricos de Salvador - Mostra de Cinemas Africanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mostradecinemasafricanos.com\/en\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/","og_locale":"en_GB","og_type":"article","og_title":"Mostra de Cinemas Africanos leva sess\u00f5es gratuitas de filmes africanos a bairros perif\u00e9ricos de Salvador - Mostra de Cinemas Africanos","og_description":"Mostra internacional leva sess\u00f5es gratuitas de filmes africanos a bairros perif\u00e9ricos de Salvador A partir de 31 de julho, Alagados, Cajazeiras e Engenho Velho de Brotas [\u2026]","og_url":"https:\/\/mostradecinemasafricanos.com\/en\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/","og_site_name":"Mostra de Cinemas Africanos","article_publisher":"https:\/\/www.facebook.com\/mostradecinemasafricanos","article_published_time":"2025-07-25T13:10:26+00:00","article_modified_time":"2026-01-02T11:38:14+00:00","og_image":[{"width":2560,"height":1438,"url":"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2022\/01\/IMG_7695-scaled.jpg","type":"image\/jpeg"}],"author":"Ana","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ana","Estimated reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/#article","isPartOf":{"@id":"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/"},"author":{"name":"Ana","@id":"https:\/\/mostradecinemasafricanos.com\/#\/schema\/person\/dd73adb8a1b08b18ecc3739f54e58de5"},"headline":"Mostra de Cinemas Africanos leva sess\u00f5es gratuitas de filmes africanos a bairros perif\u00e9ricos de Salvador","datePublished":"2025-07-25T13:10:26+00:00","dateModified":"2026-01-02T11:38:14+00:00","mainEntityOfPage":{"@id":"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/"},"wordCount":745,"publisher":{"@id":"https:\/\/mostradecinemasafricanos.com\/#organization"},"image":{"@id":"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/#primaryimage"},"thumbnailUrl":"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2022\/01\/IMG_7695-scaled.jpg","articleSection":["Not\u00edcias"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/","url":"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/","name":"Mostra de Cinemas Africanos leva sess\u00f5es gratuitas de filmes africanos a bairros perif\u00e9ricos de Salvador - Mostra de Cinemas Africanos","isPartOf":{"@id":"https:\/\/mostradecinemasafricanos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/#primaryimage"},"image":{"@id":"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/#primaryimage"},"thumbnailUrl":"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2022\/01\/IMG_7695-scaled.jpg","datePublished":"2025-07-25T13:10:26+00:00","dateModified":"2026-01-02T11:38:14+00:00","breadcrumb":{"@id":"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/#primaryimage","url":"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2022\/01\/IMG_7695-scaled.jpg","contentUrl":"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2022\/01\/IMG_7695-scaled.jpg","width":2560,"height":1438},{"@type":"BreadcrumbList","@id":"https:\/\/mostradecinemasafricanos.com\/mostra-de-cinemas-africanos-leva-sessoes-gratuitas-de-filmes-africanos-a-bairros-perifericos-de-salvador\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mostradecinemasafricanos.com\/"},{"@type":"ListItem","position":2,"name":"Mostra de Cinemas Africanos leva sess\u00f5es gratuitas de filmes africanos a bairros perif\u00e9ricos de Salvador"}]},{"@type":"WebSite","@id":"https:\/\/mostradecinemasafricanos.com\/#website","url":"https:\/\/mostradecinemasafricanos.com\/","name":"Mostra de Cinemas Africanos","description":"Brazil African Film Festival","publisher":{"@id":"https:\/\/mostradecinemasafricanos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mostradecinemasafricanos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/mostradecinemasafricanos.com\/#organization","name":"Mostra de Cinemas Africanos","url":"https:\/\/mostradecinemasafricanos.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/mostradecinemasafricanos.com\/#\/schema\/logo\/image\/","url":"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-logo-menor.png","contentUrl":"https:\/\/mostradecinemasafricanos.com\/wp-content\/uploads\/2024\/07\/mca-logo-menor.png","width":500,"height":387,"caption":"Mostra de Cinemas Africanos"},"image":{"@id":"https:\/\/mostradecinemasafricanos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mostradecinemasafricanos","https:\/\/www.instagram.com\/mostradecinemasafricanos\/"]},{"@type":"Person","@id":"https:\/\/mostradecinemasafricanos.com\/#\/schema\/person\/dd73adb8a1b08b18ecc3739f54e58de5","name":"Ana","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/31935f7c64a24c63986c2c146effe16383c15913980199ed37ed324e8a83901c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/31935f7c64a24c63986c2c146effe16383c15913980199ed37ed324e8a83901c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/31935f7c64a24c63986c2c146effe16383c15913980199ed37ed324e8a83901c?s=96&d=mm&r=g","caption":"Ana"},"url":"https:\/\/mostradecinemasafricanos.com\/en\/author\/ana\/"}]}},"_links":{"self":[{"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/posts\/11922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/comments?post=11922"}],"version-history":[{"count":2,"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/posts\/11922\/revisions"}],"predecessor-version":[{"id":11926,"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/posts\/11922\/revisions\/11926"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/media\/980"}],"wp:attachment":[{"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/media?parent=11922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/categories?post=11922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mostradecinemasafricanos.com\/en\/wp-json\/wp\/v2\/tags?post=11922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}